{"id":17938,"date":"2022-07-22T14:20:50","date_gmt":"2022-07-22T14:20:50","guid":{"rendered":"https:\/\/remaxatlantis.com\/?post_type=property&#038;p=17938"},"modified":"2023-06-28T13:35:05","modified_gmt":"2023-06-28T17:35:05","slug":"hermosa-villa-en-comunidad-cerrada","status":"publish","type":"property","link":"https:\/\/remaxatlantis.com\/es\/index.php\/property\/hermosa-villa-en-comunidad-cerrada\/","title":{"rendered":"Hermosa Villa en comunidad cerrada"},"content":{"rendered":"<h4><span style=\"font-weight: 400;\">Preciosa villa de 3 dormitorios y un modelo en Caoba con una hermosa terraza tropical&nbsp; con vistas a la piscina privada.<\/span><\/h4>\n<p><span style=\"font-weight: 400;\">Ubicado cerca de la entrada principal de una de las comunidades m\u00e1s hermosas de Sos\u00faa, cerca de \u00e1reas de juegos infantiles, canchas de tenis y baloncesto.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Esta villa est\u00e1 completamente renovada con muebles nuevos y una decoraci\u00f3n de buen gusto, ofrece un dormitorio principal en suite con un peque\u00f1o vestidor, amueblado con una cama tama\u00f1o king, televisi\u00f3n y ba\u00f1o propio, el segundo y tercer dormitorio tienen camas tama\u00f1o queen y televisores, estas dos habitaciones comparten el mismo ba\u00f1o.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">El garaje se puede convertir en un estudio con cocina americana; como granny-suite o para un ingreso de alquiler separado.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Cocina totalmente equipada perfecta para 6 personas. Totalmente amueblado y listo para entrar!!<\/span><\/p>\n<p><span style=\"font-weight: 400;\">A poca distancia de:<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">Centro de Sosua<\/span><\/li>\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">Playas<\/span><\/li>\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">Restaurantes&nbsp;<\/span><\/li>\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">Actividades para ni\u00f1os y adultos<\/span><\/li>\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">Diez minutos en coche del aeropuerto internacional de Puerto Plata<\/span><\/li>\n<\/ul>\n<h4><b>Las mejores playas de la zona son:<\/b><\/h4>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.godominicanrepublic.com\/poi\/beaches\/puerto-plata\/playa-sosua\/\"><span style=\"font-weight: 400;\">Playa Sos\u00faa<\/span><\/a><span style=\"font-weight: 400;\"> es una hermosa franja de arena dorada que contrasta con las profundas aguas turquesas y el fondo de arena blanca. De hecho, esta ciudad de la costa norte fue el punto de partida del turismo de playa en la Rep\u00fablica Dominicana y contin\u00faa hasta hoy. Lo m\u00e1s importante es que Playa Sos\u00faa es conocida por su animada zona con muchos bares, restaurantes y tiendas locales e internacionales. Adem\u00e1s, es popular entre los buceadores y los aficionados al snorkel, con f\u00e1cil acceso a muchos lugares fuera de la costa. Por ello, cientos de lugare\u00f1os y turistas acuden aqu\u00ed para disfrutar de la impresionante playa de Sos\u00faa.<\/span><\/p>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.godominicanrepublic.com\/poi\/beaches\/puerto-plata\/playa-alicia\/\"><span style=\"font-weight: 400;\">Playa Alicia<\/span><\/a><span style=\"font-weight: 400;\"> es una de las playas m\u00e1s recientes del pa\u00eds, formada hace pocos a\u00f1os. Tambi\u00e9n conocida como la \u00abplaya de los milagros\u00bb, esta playa de arena dorada se encuentra debajo de un par de restaurantes y caf\u00e9s. De hecho, este es un lugar para ir a darse un agradable ba\u00f1o y contemplar las impresionantes puestas de sol. Sin embargo, Sos\u00faa tiene mucho m\u00e1s que ofrecer, como la amabilidad de sus gentes y la variada gastronom\u00eda.<\/span><\/p>\n<h5>Art\u00edculos de inter\u00e9s:<\/h5>\n<p><a href=\"\/?p=25687\">\u2013 SOS\u00daA TIENE AEROPUERTO INTERNACIONAL<\/a><\/p>\n<p><a href=\"\/?p=25701\">\u2013 Actividades que puede realizar en Cabarete<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Preciosa villa de 3 dormitorios y un modelo en Caoba con una hermosa terraza tropical&nbsp; con vistas a la piscina privada. Ubicado cerca de la entrada principal de una de las comunidades m\u00e1s hermosas de Sos\u00faa, cerca de \u00e1reas de juegos infantiles, canchas de tenis y baloncesto. Esta villa est\u00e1 completamente renovada con muebles nuevos [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":17935,"parent":0,"menu_order":0,"template":"","property_type":[164,164],"property_status":[162,162],"property_feature":[145,366,174,145,150,150,362],"property_label":[],"property_country":[152,152],"property_state":[384],"property_city":[202,202,136],"property_area":[],"class_list":{"0":"post-17938","1":"property","2":"type-property","3":"status-publish","4":"has-post-thumbnail","5":"hentry","6":"property_type-villa-es","8":"property_status-se-vende","10":"property_feature-cesped","11":"property_feature-cocina","12":"property_feature-ducha-exterior","14":"property_feature-piscina","16":"property_feature-ventilador","17":"property_country-republica-dominicana-es-2","19":"property_state-pop-es","20":"property_city-puerto-plata-es","22":"property_city-sosua-es"},"aioseo_notices":[],"property_meta":{"fave_property_price":["350000"],"fave_property_size":["136"],"fave_property_size_prefix":["mt2"],"fave_property_land":["800"],"fave_property_land_postfix":["mt2"],"fave_property_bedrooms":["3"],"fave_property_bathrooms":["2"],"fave_additional_features_enable":["enable"],"fave_featured":["0"],"fave_mortgage_cal":["0"],"fave_payment_status":["not_paid"],"fave_agent_display_option":["author_info"],"fave_property_map_address":["Sos\u00faa, Rep\u00fablica Dominicana"],"fave_property_address":["Sos\u00faa, Puerto Plata, Rep\u00fablica Dominicana"],"houzez_geolocation_lat":["19.6664967"],"houzez_geolocation_long":["-70.491212841727"],"fave_property_location":["19.6664967,-70.491212841727,14"],"fave_property_map":["1"],"fave_property_map_street_view":["hide"],"houzez_total_property_views":["377"],"houzez_views_by_date":["a:61:{s:10:\"07-18-2024\";i:1;s:10:\"07-19-2024\";i:1;s:10:\"07-22-2024\";i:1;s:10:\"07-27-2024\";i:1;s:10:\"08-09-2024\";i:1;s:10:\"08-13-2024\";i:1;s:10:\"08-14-2024\";i:1;s:10:\"08-19-2024\";i:2;s:10:\"08-29-2024\";i:1;s:10:\"09-03-2024\";i:1;s:10:\"09-09-2024\";i:3;s:10:\"09-12-2024\";i:1;s:10:\"09-14-2024\";i:1;s:10:\"09-16-2024\";i:1;s:10:\"09-23-2024\";i:1;s:10:\"09-24-2024\";i:1;s:10:\"09-30-2024\";i:2;s:10:\"10-01-2024\";i:1;s:10:\"10-03-2024\";i:1;s:10:\"10-05-2024\";i:1;s:10:\"10-09-2024\";i:1;s:10:\"10-10-2024\";i:1;s:10:\"10-12-2024\";i:1;s:10:\"10-17-2024\";i:1;s:10:\"10-21-2024\";i:1;s:10:\"10-25-2024\";i:1;s:10:\"10-30-2024\";i:1;s:10:\"10-31-2024\";i:1;s:10:\"11-05-2024\";i:1;s:10:\"11-07-2024\";i:2;s:10:\"11-08-2024\";i:1;s:10:\"11-10-2024\";i:1;s:10:\"11-21-2024\";i:4;s:10:\"11-22-2024\";i:1;s:10:\"11-27-2024\";i:1;s:10:\"12-12-2024\";i:1;s:10:\"12-14-2024\";i:1;s:10:\"12-19-2024\";i:1;s:10:\"12-22-2024\";i:1;s:10:\"12-29-2024\";i:2;s:10:\"12-30-2024\";i:1;s:10:\"01-02-2025\";i:1;s:10:\"01-07-2025\";i:1;s:10:\"01-15-2025\";i:1;s:10:\"01-16-2025\";i:1;s:10:\"01-20-2025\";i:1;s:10:\"01-21-2025\";i:2;s:10:\"01-26-2025\";i:2;s:10:\"01-27-2025\";i:2;s:10:\"01-31-2025\";i:3;s:10:\"02-04-2025\";i:1;s:10:\"02-05-2025\";i:1;s:10:\"02-06-2025\";i:2;s:10:\"04-15-2026\";i:1;s:10:\"04-16-2026\";i:2;s:10:\"04-21-2026\";i:1;s:10:\"04-22-2026\";i:1;s:10:\"04-25-2026\";i:1;s:10:\"05-02-2026\";i:1;s:10:\"05-06-2026\";i:1;s:10:\"05-13-2026\";i:1;}"],"houzez_recently_viewed":["2026-05-13 05:48:10"],"_edit_last":["2"],"_edit_lock":["1687973797:2"],"_wpml_media_featured":["1"],"_wpml_media_duplicate":["0"],"_alp_processed":["1687973705"],"_wpml_word_count":["{\"total\":419,\"to_translate\":{\"en\":419,\"de\":419,\"ru\":419}}"],"_last_editor_used_jetpack":["block-editor"],"fave_single_top_area":["global"],"fave_single_content_area":["global"],"_aioseo_title":[null],"_aioseo_description":["Hermosa Villa de 3 habitaciones a la venta en Sosua, Republica Dominicana. Localizada en una exclusiva comunidad cerrada de la costa norte."],"_aioseo_keywords":[""],"_aioseo_og_title":[null],"_aioseo_og_description":[null],"_aioseo_og_article_section":[""],"_aioseo_og_article_tags":[""],"_aioseo_twitter_title":[null],"_aioseo_twitter_description":[null],"houzez_manual_expire":["0"],"_houzez_expiration_date_status":["saved"],"fave_loggedintoview":["0"],"_thumbnail_id":["17935"],"fave_agents":["20737"],"_wpml_media_has_media":["1"],"_b2s_post_meta":["a:7:{s:8:\"og_title\";s:34:\"Hermosa Villa en comunidad cerrada\";s:7:\"og_desc\";s:160:\"Preciosa villa de 3 dormitorios y un modelo en Caoba con una hermosa terraza tropical&nbsp; con vistas a la piscina privada.\nUbicado cerca de la entrada princip\";s:8:\"og_image\";s:64:\"https:\/\/remaxatlantis.com\/wp-content\/uploads\/2022\/07\/350k-3.jpeg\";s:12:\"og_image_alt\";s:0:\"\";s:10:\"card_title\";s:34:\"Hermosa Villa en comunidad cerrada\";s:9:\"card_desc\";s:160:\"Preciosa villa de 3 dormitorios y un modelo en Caoba con una hermosa terraza tropical&nbsp; con vistas a la piscina privada.\nUbicado cerca de la entrada princip\";s:10:\"card_image\";s:64:\"https:\/\/remaxatlantis.com\/wp-content\/uploads\/2022\/07\/350k-3.jpeg\";}"],"fave_property_images":["17934","17935","17936","17937","17930","17929","17931","17932","17933"],"_elementor_page_assets":["a:0:{}"]},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/remaxatlantis.com\/es\/index.php\/wp-json\/wp\/v2\/properties\/17938","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/remaxatlantis.com\/es\/index.php\/wp-json\/wp\/v2\/properties"}],"about":[{"href":"https:\/\/remaxatlantis.com\/es\/index.php\/wp-json\/wp\/v2\/types\/property"}],"author":[{"embeddable":true,"href":"https:\/\/remaxatlantis.com\/es\/index.php\/wp-json\/wp\/v2\/users\/3"}],"version-history":[{"count":7,"href":"https:\/\/remaxatlantis.com\/es\/index.php\/wp-json\/wp\/v2\/properties\/17938\/revisions"}],"predecessor-version":[{"id":34387,"href":"https:\/\/remaxatlantis.com\/es\/index.php\/wp-json\/wp\/v2\/properties\/17938\/revisions\/34387"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/remaxatlantis.com\/es\/index.php\/wp-json\/wp\/v2\/media\/17935"}],"wp:attachment":[{"href":"https:\/\/remaxatlantis.com\/es\/index.php\/wp-json\/wp\/v2\/media?parent=17938"}],"wp:term":[{"taxonomy":"property_type","embeddable":true,"href":"https:\/\/remaxatlantis.com\/es\/index.php\/wp-json\/wp\/v2\/property_type?post=17938"},{"taxonomy":"property_status","embeddable":true,"href":"https:\/\/remaxatlantis.com\/es\/index.php\/wp-json\/wp\/v2\/property_status?post=17938"},{"taxonomy":"property_feature","embeddable":true,"href":"https:\/\/remaxatlantis.com\/es\/index.php\/wp-json\/wp\/v2\/property_feature?post=17938"},{"taxonomy":"property_label","embeddable":true,"href":"https:\/\/remaxatlantis.com\/es\/index.php\/wp-json\/wp\/v2\/property_label?post=17938"},{"taxonomy":"property_country","embeddable":true,"href":"https:\/\/remaxatlantis.com\/es\/index.php\/wp-json\/wp\/v2\/property_country?post=17938"},{"taxonomy":"property_state","embeddable":true,"href":"https:\/\/remaxatlantis.com\/es\/index.php\/wp-json\/wp\/v2\/property_state?post=17938"},{"taxonomy":"property_city","embeddable":true,"href":"https:\/\/remaxatlantis.com\/es\/index.php\/wp-json\/wp\/v2\/property_city?post=17938"},{"taxonomy":"property_area","embeddable":true,"href":"https:\/\/remaxatlantis.com\/es\/index.php\/wp-json\/wp\/v2\/property_area?post=17938"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}