{"id":38122,"date":"2023-04-11T10:52:46","date_gmt":"2023-04-11T14:52:46","guid":{"rendered":"https:\/\/remaxatlantis.com\/?post_type=property&#038;p=38122"},"modified":"2024-01-09T12:32:09","modified_gmt":"2024-01-09T16:32:09","slug":"exclusivo-terreno-con-vista-al-mar","status":"houzez_sold","type":"property","link":"https:\/\/remaxatlantis.com\/es\/index.php\/property\/exclusivo-terreno-con-vista-al-mar\/","title":{"rendered":"Exclusivo terreno con vista al Mar"},"content":{"rendered":"<p>Este exclusivo terreno ubicado en Sos\u00faa a solo minutos del centro y con una vista magn\u00edfica.<\/p>\n<p>Este terreno esta en un grandioso lugar donde la tranquilidad reina, con una vista que te enamora a cada instante.<\/p>\n<p>Puedes asegurar tu inversi\u00f3n en este terreno, si quieres hacer una villa o apartamentos para hacer Airbnb o la casa de tu sue\u00f1os.<\/p>\n<p>Sos\u00faa tiene una excelente buena infraestructura, carreteras pavimentadas, supermercados, bancos, cl\u00ednica de emergencia, farmacias, restaurantes, excelentes escuelas internacionales, y todas las cosas importantes para la vida diaria.<\/p>\n<h2>Acerca de Sos\u00faa<\/h2>\n<p>Sos\u00faa es una ciudad costera de la provincia de Puerto Plata, en la Rep\u00fablica Dominicana. Se encuentra a unos 6,4 km del aeropuerto internacional Gregorio Luper\u00f3n de San Felipe de Puerto Plata.La ciudad est\u00e1 dividida en tres sectores: El Batey, que es la principal secci\u00f3n tur\u00edstica y en el lado este de la playa principal (Playa Sos\u00faa)<\/p>\n<h3>Las mejores Playas de la zona son:<\/h3>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.godominicanrepublic.com\/es\/poi\/familia\/puerto-plata-es\/playa-sosua\/\">Playa Sos\u00faa<\/a>, a tan solo veinte minutos al este de Puerto Plata, las arenas doradas de Playa Sos\u00faa abrazan la bah\u00eda en forma de media luna creando un contraste con sus aguas azul turquesa con un fondo blanco y arenoso. Esta playa fue pr\u00e1cticamente donde origin\u00f3 el turismo de playa en Rep\u00fablica Dominicana, y contin\u00faa siendo un destino importante. Playa Sos\u00faa es conocida por su animado tramo repleto de bares, restaurantes y tiendas locales e internacionales.<\/p>\n<p><a rel=\"nofollow\" href=\"https:\/\/www.godominicanrepublic.com\/es\/poi\/familia\/puerto-plata-es\/playa-alicia\/\">Playa Alicia<\/a> es una de las playas m\u00e1s recientes del pa\u00eds, formada hace unos a\u00f1os atr\u00e1s. Tambi\u00e9n conocida como la \u201cplaya milagrosa\u201d, este amplio tramo de arena dorada se encuentra debajo de un par de restaurantes y caf\u00e9s, pero no encontrar\u00e1s ning\u00fan otro negocio o vendedores en la playa. Es un lugar para ir a nadar tranquilamente y disfrutar de las impresionantes puestas de sol.<\/p>\n<h3>Articulos de interes:<\/h3>\n<ul>\n<li><a href=\"\/?p=25625\">\u00bfC\u00f3mo Mejorar Tu Historial Crediticio Para Financiar Tu Casa?<\/a><\/li>\n<li><a href=\"\/?p=25687\">\u00a1SOS\u00daA TIENE AEROPUERTO INTERNACIONAL!<\/a><\/li>\n<li><a href=\"\/?p=25701\">Actividades que puedes realizar en Cabarete<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Este exclusivo terreno ubicado en Sos\u00faa a solo minutos del centro y con una vista magn\u00edfica. Este terreno esta en un grandioso lugar donde la tranquilidad reina, con una vista que te enamora a cada instante. Puedes asegurar tu inversi\u00f3n en este terreno, si quieres hacer una villa o apartamentos para hacer Airbnb o la [&hellip;]<\/p>\n","protected":false},"author":22,"featured_media":38110,"parent":0,"menu_order":0,"template":"","property_type":[215],"property_status":[399],"property_feature":[],"property_label":[159],"property_country":[152],"property_state":[384],"property_city":[136],"property_area":[],"class_list":["post-38122","property","type-property","status-houzez_sold","has-post-thumbnail","hentry","property_type-terrenos","property_status-vendido","property_label-oferta-caliente","property_country-republica-dominicana-es-2","property_state-pop-es","property_city-sosua-es"],"aioseo_notices":[],"property_meta":{"_alp_processed":["1704817929"],"fave_property_price":["78285"],"fave_property_size":["921"],"fave_property_size_prefix":["m\u00b2"],"fave_property_land":["921"],"fave_property_land_postfix":["m\u00b2"],"_thumbnail_id":["38110"],"fave_additional_features_enable":["enable"],"fave_featured":["0"],"fave_mortgage_cal":["0"],"fave_payment_status":["not_paid"],"fave_agents":["22189"],"fave_agent_display_option":["author_info"],"_wpml_word_count":["{\"total\":376,\"to_translate\":{\"en\":376,\"de\":376,\"ru\":376}}"],"_edit_lock":["1697572626:16"],"_last_editor_used_jetpack":["block-editor"],"_edit_last":["16"],"_b2s_post_meta":["a:7:{s:8:\"og_title\";s:34:\"Exclusivo terreno con vista al Mar\";s:7:\"og_desc\";s:160:\"Este exclusivo terreno ubicado en Sos\u00faa a solo minutos del centro y con una vista magn\u00edfica.\n\nEste terreno esta en un grandioso lugar donde la tranquilidad re\";s:8:\"og_image\";s:0:\"\";s:12:\"og_image_alt\";s:0:\"\";s:10:\"card_title\";s:34:\"Exclusivo terreno con vista al Mar\";s:9:\"card_desc\";s:160:\"Este exclusivo terreno ubicado en Sos\u00faa a solo minutos del centro y con una vista magn\u00edfica.\n\nEste terreno esta en un grandioso lugar donde la tranquilidad re\";s:10:\"card_image\";s:0:\"\";}"],"fave_property_map_address":["Sos\u00faa, Puerto Plata, Rep\u00fablica Dominicana"],"fave_property_location":["25.68654,-80.431345,14"],"houzez_geolocation_lat":["25.68654"],"houzez_geolocation_long":["-80.431345"],"fave_property_map_street_view":["hide"],"fave_single_top_area":["global"],"fave_single_content_area":["global"],"_aioseo_title":[null],"_aioseo_description":["Este exclusivo terreno ubicado en Sos\u00faa a solo minutos del centro y con una vista magn\u00edfica. Este terreno esta en un grandioso lugar donde la tranquilidad reina"],"_aioseo_keywords":[""],"_aioseo_og_title":[null],"_aioseo_og_description":[null],"_aioseo_og_article_section":[""],"_aioseo_og_article_tags":[""],"_aioseo_twitter_title":[null],"_aioseo_twitter_description":[null],"_wpml_media_has_media":["1"],"houzez_manual_expire":["0"],"_houzez_expiration_date_status":["saved"],"_wpml_media_duplicate":["0"],"_wpml_media_featured":["0"],"houzez_total_property_views":["116"],"houzez_views_by_date":["a:61:{s:10:\"07-08-2023\";i:1;s:10:\"07-09-2023\";i:1;s:10:\"07-18-2023\";i:2;s:10:\"07-19-2023\";i:1;s:10:\"07-24-2023\";i:1;s:10:\"07-27-2023\";i:1;s:10:\"07-28-2023\";i:1;s:10:\"07-30-2023\";i:1;s:10:\"08-01-2023\";i:1;s:10:\"08-03-2023\";i:1;s:10:\"08-04-2023\";i:1;s:10:\"08-05-2023\";i:1;s:10:\"08-09-2023\";i:2;s:10:\"08-11-2023\";i:1;s:10:\"08-12-2023\";i:2;s:10:\"08-16-2023\";i:1;s:10:\"08-17-2023\";i:1;s:10:\"08-22-2023\";i:1;s:10:\"08-24-2023\";i:1;s:10:\"08-26-2023\";i:1;s:10:\"08-29-2023\";i:1;s:10:\"09-14-2023\";i:1;s:10:\"09-19-2023\";i:1;s:10:\"09-22-2023\";i:1;s:10:\"09-25-2023\";i:2;s:10:\"09-27-2023\";i:2;s:10:\"10-02-2023\";i:1;s:10:\"10-04-2023\";i:1;s:10:\"10-10-2023\";i:1;s:10:\"10-14-2023\";i:1;s:10:\"10-15-2023\";i:1;s:10:\"10-17-2023\";i:2;s:10:\"10-23-2023\";i:1;s:10:\"10-25-2023\";i:1;s:10:\"10-29-2023\";i:1;s:10:\"10-30-2023\";i:3;s:10:\"10-31-2023\";i:1;s:10:\"11-02-2023\";i:1;s:10:\"11-10-2023\";i:1;s:10:\"11-13-2023\";i:2;s:10:\"11-17-2023\";i:2;s:10:\"11-21-2023\";i:1;s:10:\"12-01-2023\";i:1;s:10:\"12-02-2023\";i:1;s:10:\"12-05-2023\";i:1;s:10:\"12-06-2023\";i:2;s:10:\"12-14-2023\";i:1;s:10:\"12-18-2023\";i:1;s:10:\"12-22-2023\";i:1;s:10:\"12-24-2023\";i:2;s:10:\"12-26-2023\";i:1;s:10:\"12-30-2023\";i:1;s:10:\"01-02-2024\";i:1;s:10:\"01-06-2024\";i:1;s:10:\"01-07-2024\";i:1;s:10:\"02-07-2025\";i:1;s:10:\"04-16-2026\";i:1;s:10:\"04-21-2026\";i:1;s:10:\"04-24-2026\";i:1;s:10:\"05-01-2026\";i:1;s:10:\"05-13-2026\";i:1;}"],"houzez_recently_viewed":["2026-05-13 06:11:16"],"fave_property_images":["38110","38114","38118"],"_elementor_page_assets":["a:0:{}"]},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/remaxatlantis.com\/es\/index.php\/wp-json\/wp\/v2\/properties\/38122","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/remaxatlantis.com\/es\/index.php\/wp-json\/wp\/v2\/properties"}],"about":[{"href":"https:\/\/remaxatlantis.com\/es\/index.php\/wp-json\/wp\/v2\/types\/property"}],"author":[{"embeddable":true,"href":"https:\/\/remaxatlantis.com\/es\/index.php\/wp-json\/wp\/v2\/users\/22"}],"version-history":[{"count":3,"href":"https:\/\/remaxatlantis.com\/es\/index.php\/wp-json\/wp\/v2\/properties\/38122\/revisions"}],"predecessor-version":[{"id":44640,"href":"https:\/\/remaxatlantis.com\/es\/index.php\/wp-json\/wp\/v2\/properties\/38122\/revisions\/44640"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/remaxatlantis.com\/es\/index.php\/wp-json\/wp\/v2\/media\/38110"}],"wp:attachment":[{"href":"https:\/\/remaxatlantis.com\/es\/index.php\/wp-json\/wp\/v2\/media?parent=38122"}],"wp:term":[{"taxonomy":"property_type","embeddable":true,"href":"https:\/\/remaxatlantis.com\/es\/index.php\/wp-json\/wp\/v2\/property_type?post=38122"},{"taxonomy":"property_status","embeddable":true,"href":"https:\/\/remaxatlantis.com\/es\/index.php\/wp-json\/wp\/v2\/property_status?post=38122"},{"taxonomy":"property_feature","embeddable":true,"href":"https:\/\/remaxatlantis.com\/es\/index.php\/wp-json\/wp\/v2\/property_feature?post=38122"},{"taxonomy":"property_label","embeddable":true,"href":"https:\/\/remaxatlantis.com\/es\/index.php\/wp-json\/wp\/v2\/property_label?post=38122"},{"taxonomy":"property_country","embeddable":true,"href":"https:\/\/remaxatlantis.com\/es\/index.php\/wp-json\/wp\/v2\/property_country?post=38122"},{"taxonomy":"property_state","embeddable":true,"href":"https:\/\/remaxatlantis.com\/es\/index.php\/wp-json\/wp\/v2\/property_state?post=38122"},{"taxonomy":"property_city","embeddable":true,"href":"https:\/\/remaxatlantis.com\/es\/index.php\/wp-json\/wp\/v2\/property_city?post=38122"},{"taxonomy":"property_area","embeddable":true,"href":"https:\/\/remaxatlantis.com\/es\/index.php\/wp-json\/wp\/v2\/property_area?post=38122"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}